{"id":1991,"date":"2021-02-10T10:16:16","date_gmt":"2021-02-10T13:16:16","guid":{"rendered":"https:\/\/fortflex.com.br\/loja\/?post_type=product&#038;p=1991"},"modified":"2021-07-02T09:59:38","modified_gmt":"2021-07-02T12:59:38","slug":"1991","status":"publish","type":"product","link":"https:\/\/fortflex.com.br\/loja\/produto\/1991\/","title":{"rendered":"Cadeira\/Poltrona Girat\u00f3ria 4.000 &#8211; (Relax\/Base Preta)"},"content":{"rendered":"<p>&#8211; Assento e Encosto em espuma poliuretano injetada (Espessura 70mm), com ou sem gomos.<br \/>\n&#8211; Encosto Alto Presidente<br \/>\n&#8211; Base girat\u00f3ria em a\u00e7o com capa preta<br \/>\n&#8211; Mecanismo Relax<br \/>\n&#8211; Rod\u00edzios em PP<br \/>\n&#8211; Inclina\u00e7\u00e3o no encosto com bloqueio em 1 posi\u00e7\u00e3o<br \/>\n&#8211; Regulagem de altura do assento a g\u00e1s<br \/>\n&#8211; Revestimento em diversas op\u00e7\u00f5es<br \/>\n&#8211; Bra\u00e7os fixo ou regul\u00e1vel em altura, acabamento preto em PP.<br \/>\n&#8211; Peso m\u00e1ximo suportado: 120kg<br \/>\nGarantia: 12 meses<\/p>\n<p>Medidas:<br \/>\nEncosto: 465mm larg. x 620mm alt.<br \/>\nAlt. encosto: 1070mm m\u00edn. x 1160mm m\u00e1x.<br \/>\nAssento: 490 mm larg. x 480mm prof.<br \/>\nAlt. assento: 460mm m\u00edn. x 550mm m\u00e1x.<\/p>\n<p>&#8211; O prazo de envio do seu pedido fica em <strong>at\u00e9 30 dias corridos<\/strong> ap\u00f3s a confirma\u00e7\u00e3o do pagamento. Pedidos aprovados ap\u00f3s \u00e0s 17:30h, nos finais de semana ou feriados, come\u00e7am a contar o prazo somente no segundo dia \u00fatil subsequente.<br \/>\nMaiores informa\u00e7\u00f5es entre em contato conosco.<br \/>\nInstru\u00e7\u00f5es de limpeza: n\u00e3o utilizar produtos abrasivos, limpar com flanela ou pano \u00famido e sab\u00e3o neutro.<br \/>\n-Produto Nacional.<br \/>\n-Imagens meramente ilustrativas<br \/>\n&#8211; Montagem feita pelo cliente ou entrar em contato por email ou whatsapp para cadeiras montadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8211; Assento e Encosto em espuma poliuretano injetada (Espessura 70mm), com ou sem gomos. &#8211; Encosto Alto Presidente &#8211; Base girat\u00f3ria em a\u00e7o com capa preta &#8211; Mecanismo Relax &#8211; Rod\u00edzios em PP &#8211; Inclina\u00e7\u00e3o no encosto com bloqueio em 1 posi\u00e7\u00e3o &#8211; Regulagem de altura do assento a g\u00e1s &#8211; Revestimento em diversas op\u00e7\u00f5es [&#8230;]\n","protected":false},"featured_media":1992,"template":"","meta":[],"product_cat":[109],"product_tag":[],"_links":{"self":[{"href":"https:\/\/fortflex.com.br\/loja\/wp-json\/wp\/v2\/product\/1991"}],"collection":[{"href":"https:\/\/fortflex.com.br\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/fortflex.com.br\/loja\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fortflex.com.br\/loja\/wp-json\/wp\/v2\/media\/1992"}],"wp:attachment":[{"href":"https:\/\/fortflex.com.br\/loja\/wp-json\/wp\/v2\/media?parent=1991"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/fortflex.com.br\/loja\/wp-json\/wp\/v2\/product_cat?post=1991"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/fortflex.com.br\/loja\/wp-json\/wp\/v2\/product_tag?post=1991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}